{"id":29,"date":"2021-05-13T12:57:14","date_gmt":"2021-05-13T10:57:14","guid":{"rendered":"http:\/\/www.roelofs-metaal.com\/?page_id=29"},"modified":"2022-02-24T08:38:51","modified_gmt":"2022-02-24T06:38:51","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.roelofs-metaal.com\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p><img class=\"alignnone size-medium wp-image-353\" src=\"http:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow-300x87.png\" alt=\"\" width=\"300\" height=\"87\" srcset=\"https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow-200x58.png 200w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow-300x87.png 300w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow-400x116.png 400w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow-600x174.png 600w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow-768x222.png 768w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow-800x232.png 800w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/08\/Roelofs-Metaal-logo-glow.png 815w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 <img class=\"wp-image-417 alignright\" src=\"http:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo-300x77.png\" alt=\"\" width=\"226\" height=\"58\" srcset=\"https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo-200x51.png 200w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo-300x77.png 300w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo-400x102.png 400w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo-600x154.png 600w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo-768x197.png 768w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo-800x205.png 800w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/metaalunie-lid-logo.png 820w\" sizes=\"(max-width: 226px) 100vw, 226px\" \/><\/p>\n<p><span class=\"contact-street\">Roelofs\u00aeMetaal Nederland BV<br \/>\nDrieboomlaan 116<br \/>\n1624 BP HOORN<br \/>\nNederland<\/span><\/p>\n<p>KvK-nummer: 82672563<\/p>\n<p>BTW-nummer: NL862561449B01<\/p>\n<p>EORI : NL862561449<\/p>\n<hr \/>\n<p>Contactpersoon Non Ferro:<\/p>\n<p><img class=\"alignnone wp-image-423\" src=\"http:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-225x300.jpg\" alt=\"\" width=\"83\" height=\"111\" srcset=\"https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-200x267.jpg 200w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-225x300.jpg 225w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-400x533.jpg 400w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-600x800.jpg 600w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-768x1024.jpg 768w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-800x1067.jpg 800w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-1152x1536.jpg 1152w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-1200x1600.jpg 1200w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-1536x2048.jpg 1536w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_3029-scaled.jpg 1920w\" sizes=\"(max-width: 83px) 100vw, 83px\" \/><\/p>\n<p>Uw contactpersoon is Bert Roelofs<\/p>\n<p>mobiel: + 31 6 515 80 365.<\/p>\n<hr \/>\n<p>Contactpersoon Ferro:<\/p>\n<p><img class=\"wp-image-422 alignleft\" src=\"http:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-204x300.jpg\" alt=\"\" width=\"83\" height=\"122\" srcset=\"https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-200x294.jpg 200w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-204x300.jpg 204w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-400x588.jpg 400w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-600x882.jpg 600w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-697x1024.jpg 697w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-768x1129.jpg 768w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765-800x1176.jpg 800w, https:\/\/www.roelofs-metaal.com\/wp-content\/uploads\/2021\/11\/IMG_4765.jpg 871w\" sizes=\"(max-width: 83px) 100vw, 83px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Uw contactpersoon is Fred Lichteveld<\/p>\n<p>mobiel: +31 6 30 96 64 45.<\/p>\n<hr \/>\n<p>Bereikbaarheid:<br \/>\nU kunt ons telefonisch bereiken op:\u00a0+ 31 229 26 76 21<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 Roelofs\u00aeMetaal Nederland BV Drieboomlaan 116 1624 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/pages\/29"}],"collection":[{"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":13,"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/pages\/29\/revisions"}],"predecessor-version":[{"id":624,"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/pages\/29\/revisions\/624"}],"wp:attachment":[{"href":"https:\/\/www.roelofs-metaal.com\/en\/wp-json\/wp\/v2\/media?parent=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}